{"id":1932,"date":"2016-11-17T10:15:53","date_gmt":"2016-11-17T13:15:53","guid":{"rendered":"http:\/\/www.rotaseguros.com.br\/corretor\/?p=1932"},"modified":"2016-11-17T10:21:13","modified_gmt":"2016-11-17T13:21:13","slug":"reajuste-do-coeficiente-de-reembolso-de-seguro-crs-bradesco","status":"publish","type":"post","link":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/2016\/11\/17\/reajuste-do-coeficiente-de-reembolso-de-seguro-crs-bradesco\/","title":{"rendered":"Reajuste do Coeficiente de Reembolso de Seguro (CRS) | Bradesco"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Comunicado Bradesco<\/strong><\/p>\n<p>Prezados,<\/p>\n<p>&nbsp;<\/p>\n<p>Afim de municia-los de informa\u00e7\u00f5es para que possamos vender cada vez mais, segue em anexo tabela com exemplos de reembolso, v\u00e1lida somente para ap\u00f3lices contratadas a partir de 01\/11\/2016.<\/p>\n<ul>\n<li><a href=\"http:\/\/www.rotaseguros.com.br\/corretor\/wp-content\/uploads\/Exemplos-Reembolso-ACIMA-30-VIDAS-11.2016.pdf\" target=\"_blank\">exemplos-reembolso-acima-30-vidas-11-2016<\/a><\/li>\n<li><a href=\"http:\/\/www.rotaseguros.com.br\/corretor\/wp-content\/uploads\/Exemplos-Reembolso-ATE-29-VIDAS-11.2016.pdf\" target=\"_blank\">exemplos-reembolso-ate-29-vidas-11-2016<\/a><\/li>\n<\/ul>\n<p>Para ap\u00f3lices anteriores a 01\/11\/2016, os valores de reembolso est\u00e3o dispon\u00edveis no site do segurado, com acesso via senha pessoal.<\/p>\n<p>&nbsp;<\/p>\n<p>D\u00favidas, estamos \u00e0 disposi\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comunicado Bradesco Prezados, &nbsp; Afim de municia-los de informa\u00e7\u00f5es para que possamos vender cada vez mais, segue em anexo tabela com exemplos de reembolso, v\u00e1lida somente para ap\u00f3lices contratadas a &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,19],"tags":[329],"class_list":["post-1932","post","type-post","status-publish","format-standard","hentry","category-bradesco","category-comunicados","tag-reembolso-de-seguro-bradesco"],"_links":{"self":[{"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/posts\/1932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/comments?post=1932"}],"version-history":[{"count":0,"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/posts\/1932\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/media?parent=1932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/categories?post=1932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/tags?post=1932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}