{"id":3511,"date":"2017-05-19T09:31:10","date_gmt":"2017-05-19T12:31:10","guid":{"rendered":"http:\/\/www.rotaseguros.com.br\/corretor\/?p=3511"},"modified":"2017-05-19T09:34:13","modified_gmt":"2017-05-19T12:34:13","slug":"carencias-promocionais-vivamedtabela-atualizada-prime","status":"publish","type":"post","link":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/2017\/05\/19\/carencias-promocionais-vivamedtabela-atualizada-prime\/","title":{"rendered":"CAR\u00caNCIAS PROMOCIONAIS  VIVAMED\/TABELA ATUALIZADA | Prime"},"content":{"rendered":"<p>Prezados,<\/p>\n<p>&nbsp;<\/p>\n<p>Abaixo,\u00a0segue a TABELA DE VENDAS \u2013 VIVAMED, com a \u00faltima atualiza\u00e7\u00e3o.<\/p>\n<p>Aproveitamos a oportunidade para enviar os Aditivos utilizados nas vendas da VIVAMED.<\/p>\n<ul>\n<li><a href=\"http:\/\/www.rotaseguros.com.br\/corretor\/wp-content\/uploads\/MAIO-17-MANUAL-DE-VENDAS-VIVAMED-CORRETORES.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">MAIO 17 &#8211; MANUAL DE VENDAS VIVAMED CORRETORES<\/a><\/li>\n<li><a href=\"http:\/\/www.rotaseguros.com.br\/corretor\/wp-content\/uploads\/ADITIVO-VIVAMED-VARIACAO-E-COPARTICIPACAO.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">ADITIVO VIVAMED VARIACAO E COPARTICIPACAO<\/a><\/li>\n<li><a href=\"http:\/\/www.rotaseguros.com.br\/corretor\/wp-content\/uploads\/ADITIVO-VIVAMED-COMPRA-CARENCIA.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">ADITIVO VIVAMED COMPRA CARENCIA<\/a><\/li>\n<\/ul>\n<p><strong><u>ESTAMOS COM ADITIVO PROMOCIONAL PARA NOVOS USU\u00c1RIOS COM REDU\u00c7\u00c3O DE CAR\u00caNCIAS!<\/u><\/strong><\/p>\n<p><a href=\"http:\/\/www.rotaseguros.com.br\/corretor\/wp-content\/uploads\/Prime-Adm.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-3515\" src=\"http:\/\/www.rotaseguros.com.br\/corretor\/wp-content\/uploads\/Prime-Adm.jpg\" alt=\"\" width=\"261\" height=\"186\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prezados, &nbsp; Abaixo,\u00a0segue a TABELA DE VENDAS \u2013 VIVAMED, com a \u00faltima atualiza\u00e7\u00e3o. Aproveitamos a oportunidade para enviar os Aditivos utilizados nas vendas da VIVAMED. MAIO 17 &#8211; MANUAL DE &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,276,17],"tags":[455],"class_list":["post-3511","post","type-post","status-publish","format-standard","hentry","category-comunicados","category-prime-beneficios","category-vivamed","tag-tabela-vivamed-prime"],"_links":{"self":[{"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/posts\/3511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/comments?post=3511"}],"version-history":[{"count":0,"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/posts\/3511\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/media?parent=3511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/categories?post=3511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/tags?post=3511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}