{"id":5223,"date":"2017-12-14T09:49:27","date_gmt":"2017-12-14T12:49:27","guid":{"rendered":"http:\/\/www.rotaseguros.com.br\/corretor\/?p=5223"},"modified":"2017-12-14T09:49:27","modified_gmt":"2017-12-14T12:49:27","slug":"comunicado-medsenior","status":"publish","type":"post","link":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/2017\/12\/14\/comunicado-medsenior\/","title":{"rendered":"Comunicado MedS\u00eanior"},"content":{"rendered":"<p>Prezados Parceiros,<\/p>\n<p>Comunicamos que devido a problemas t\u00e9cnicos da Operadora de telefonia, o n\u00famero de atendimento ao cliente Meds\u00eanior 4062-7070 divulgado nos materiais de vendas est\u00e1 indispon\u00edvel.<\/p>\n<p><strong>Pedimos que todos o nossos corretores e clientes sejam orientados a utilizar o n\u00famero 0800 605 5505.<\/strong><\/p>\n<p>Nos pr\u00f3ximos dias ser\u00e1 feita a substitui\u00e7\u00e3o de todo o material de vendas.<br \/>\nAgradecemos a compreens\u00e3o.<\/p>\n<p>Meds\u00eanior<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prezados Parceiros, Comunicamos que devido a problemas t\u00e9cnicos da Operadora de telefonia, o n\u00famero de atendimento ao cliente Meds\u00eanior 4062-7070 divulgado nos materiais de vendas est\u00e1 indispon\u00edvel. Pedimos que todos &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,471],"tags":[],"class_list":["post-5223","post","type-post","status-publish","format-standard","hentry","category-comunicados","category-medsenior"],"_links":{"self":[{"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/posts\/5223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/comments?post=5223"}],"version-history":[{"count":0,"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/posts\/5223\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/media?parent=5223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/categories?post=5223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rotaseguros.com.br\/corretor\/index.php\/wp-json\/wp\/v2\/tags?post=5223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}